{"id":7715,"date":"2018-12-03T13:56:34","date_gmt":"2018-12-03T12:56:34","guid":{"rendered":"https:\/\/www.rijeka.hr\/it\/?page_id=7715"},"modified":"2018-12-03T14:18:46","modified_gmt":"2018-12-03T13:18:46","slug":"centro-informativo-per-la-prevenzione-della-criminalita","status":"publish","type":"page","link":"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/vivere-una-citta-sicura\/centro-informativo-per-la-prevenzione-della-criminalita\/","title":{"rendered":"Centro informativo per la prevenzione della criminalit\u00e0"},"content":{"rendered":"<p>Il Centro informativo per la prevenzione della criminalit\u00e0 \u00e8 stato istituito in cooperazione tra la citt\u00e0 di Fiume e la Questura della Regione litoraneo \u2013 montana in modo tale da aumentare la sicurezza, prevenire comportamenti dannosi, ridurre la paura della criminalit\u00e0 tra i cittadini, migliorare la qualit\u00e0 della vita sul territorio della citt\u00e0 di Fiume, con l&#8217;attuazione di una serie di attivit\u00e0 e l&#8217;attivit\u00e0 congiunta e coordinata di tutta la comunit\u00e0.<\/p>\n<p>Tutte le\u00a0informazioni sono disponibili presso il Centro informativo, inoltre si possono ricevere chiamando il numero di telefono: 209 369 o via e-mail: &#x76;&#105;j&#x65;&#x63;&#101;p&#x6b;&#x40;&#114;i&#x6a;&#x65;&#107;a&#x2e;&#x68;&#114;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Centro informativo per la prevenzione della criminalit\u00e0 \u00e8 stato istituito in cooperazione tra la citt\u00e0 di Fiume e la Questura della Regione litoraneo \u2013 montana in modo tale da aumentare la sicurezza, prevenire comportamenti dannosi, ridurre la paura della criminalit\u00e0 tra i cittadini, migliorare la qualit\u00e0 della vita sul territorio della citt\u00e0 di Fiume,&#8230;<\/p>\n","protected":false},"author":12,"featured_media":0,"parent":7712,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"footnotes":"","_links_to":"","_links_to_target":""},"tags":[],"class_list":["post-7715","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Centro informativo per la prevenzione della criminalit\u00e0 - Citt\u00e0 di Fiume<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/vivere-una-citta-sicura\/centro-informativo-per-la-prevenzione-della-criminalita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centro informativo per la prevenzione della criminalit\u00e0 - Citt\u00e0 di Fiume\" \/>\n<meta property=\"og:description\" content=\"Il Centro informativo per la prevenzione della criminalit\u00e0 \u00e8 stato istituito in cooperazione tra la citt\u00e0 di Fiume e la Questura della Regione litoraneo \u2013 montana in modo tale da aumentare la sicurezza, prevenire comportamenti dannosi, ridurre la paura della criminalit\u00e0 tra i cittadini, migliorare la qualit\u00e0 della vita sul territorio della citt\u00e0 di Fiume,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/vivere-una-citta-sicura\/centro-informativo-per-la-prevenzione-della-criminalita\/\" \/>\n<meta property=\"og:site_name\" content=\"Citt\u00e0 di Fiume\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-03T13:18:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/vivere-una-citta-sicura\/centro-informativo-per-la-prevenzione-della-criminalita\/\",\"url\":\"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/vivere-una-citta-sicura\/centro-informativo-per-la-prevenzione-della-criminalita\/\",\"name\":\"Centro informativo per la prevenzione della criminalit\u00e0 - Citt\u00e0 di Fiume\",\"isPartOf\":{\"@id\":\"https:\/\/www.rijeka.hr\/it\/#website\"},\"datePublished\":\"2018-12-03T12:56:34+00:00\",\"dateModified\":\"2018-12-03T13:18:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/vivere-una-citta-sicura\/centro-informativo-per-la-prevenzione-della-criminalita\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/vivere-una-citta-sicura\/centro-informativo-per-la-prevenzione-della-criminalita\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/vivere-una-citta-sicura\/centro-informativo-per-la-prevenzione-della-criminalita\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna stranica\",\"item\":\"https:\/\/www.rijeka.hr\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Temi per i cittadini\",\"item\":\"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Abitazione ed edilizia\",\"item\":\"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Sicurezza giornaliera\",\"item\":\"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Vivere in una citt\u00e0 sicura\",\"item\":\"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/vivere-una-citta-sicura\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Centro informativo per la prevenzione della criminalit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.rijeka.hr\/it\/#website\",\"url\":\"https:\/\/www.rijeka.hr\/it\/\",\"name\":\"Citt\u00e0 di Fiume\",\"description\":\"Portale web della Citta&#039; di Fiume\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.rijeka.hr\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centro informativo per la prevenzione della criminalit\u00e0 - Citt\u00e0 di Fiume","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/vivere-una-citta-sicura\/centro-informativo-per-la-prevenzione-della-criminalita\/","og_locale":"it_IT","og_type":"article","og_title":"Centro informativo per la prevenzione della criminalit\u00e0 - Citt\u00e0 di Fiume","og_description":"Il Centro informativo per la prevenzione della criminalit\u00e0 \u00e8 stato istituito in cooperazione tra la citt\u00e0 di Fiume e la Questura della Regione litoraneo \u2013 montana in modo tale da aumentare la sicurezza, prevenire comportamenti dannosi, ridurre la paura della criminalit\u00e0 tra i cittadini, migliorare la qualit\u00e0 della vita sul territorio della citt\u00e0 di Fiume,...","og_url":"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/vivere-una-citta-sicura\/centro-informativo-per-la-prevenzione-della-criminalita\/","og_site_name":"Citt\u00e0 di Fiume","article_modified_time":"2018-12-03T13:18:46+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/vivere-una-citta-sicura\/centro-informativo-per-la-prevenzione-della-criminalita\/","url":"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/vivere-una-citta-sicura\/centro-informativo-per-la-prevenzione-della-criminalita\/","name":"Centro informativo per la prevenzione della criminalit\u00e0 - Citt\u00e0 di Fiume","isPartOf":{"@id":"https:\/\/www.rijeka.hr\/it\/#website"},"datePublished":"2018-12-03T12:56:34+00:00","dateModified":"2018-12-03T13:18:46+00:00","breadcrumb":{"@id":"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/vivere-una-citta-sicura\/centro-informativo-per-la-prevenzione-della-criminalita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/vivere-una-citta-sicura\/centro-informativo-per-la-prevenzione-della-criminalita\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/vivere-una-citta-sicura\/centro-informativo-per-la-prevenzione-della-criminalita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna stranica","item":"https:\/\/www.rijeka.hr\/it\/"},{"@type":"ListItem","position":2,"name":"Temi per i cittadini","item":"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/"},{"@type":"ListItem","position":3,"name":"Abitazione ed edilizia","item":"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/"},{"@type":"ListItem","position":4,"name":"Sicurezza giornaliera","item":"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/"},{"@type":"ListItem","position":5,"name":"Vivere in una citt\u00e0 sicura","item":"https:\/\/www.rijeka.hr\/it\/temi-per-i-cittadini\/abitazione-ed-edilizia\/sicurezza-giornaliera\/vivere-una-citta-sicura\/"},{"@type":"ListItem","position":6,"name":"Centro informativo per la prevenzione della criminalit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.rijeka.hr\/it\/#website","url":"https:\/\/www.rijeka.hr\/it\/","name":"Citt\u00e0 di Fiume","description":"Portale web della Citta&#039; di Fiume","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rijeka.hr\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/pages\/7715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/comments?post=7715"}],"version-history":[{"count":5,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/pages\/7715\/revisions"}],"predecessor-version":[{"id":7720,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/pages\/7715\/revisions\/7720"}],"up":[{"embeddable":true,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/pages\/7712"}],"wp:attachment":[{"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/media?parent=7715"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/tags?post=7715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}