{"id":14183,"date":"2022-01-31T12:03:38","date_gmt":"2022-01-31T11:03:38","guid":{"rendered":"https:\/\/www.rijeka.hr\/it\/?p=14183"},"modified":"2022-05-19T11:40:16","modified_gmt":"2022-05-19T09:40:16","slug":"pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo","status":"publish","type":"post","link":"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/","title":{"rendered":"Pubblicato l\u2019Invito a presentare manifestazioni di interesse rivolto agli imprenditori per l\u2019acquisto di lotti nella Zona imprenditoriale Bodulovo"},"content":{"rendered":"<p>La Zona imprenditoriale Bodulovo \u00e8 uno dei progetti infrastrutturali della Citt\u00e0 di Fiume il cui obiettivo \u00e8 quello di ampliare il sistema di supporto infrastrutturale alle piccole e medie imprese attraverso la creazione di una zona imprenditoriale funzionale e operativa, completamente attrezzata con moderne infrastrutture comuni di base e aggiuntive.<\/p>\n<p>L&#8217;obiettivo \u00e8 quello di consentire una maggiore competitivit\u00e0 delle piccole e medie imprese esistenti, aumentare il numero di nuove imprese e consentire nuovi investimenti e una maggiore crescita occupazionale.<\/p>\n<p>L&#8217;invito rivolto agli imprenditori a presentare manifestazioni di interesse per l&#8217;acquisto di terreni edificabili nella Zona imprenditoriale di Bodulovo \u00e8 stato preparato dal Dipartimento dell\u2019imprenditoria della Citt\u00e0 di Fiume in collaborazione con il Dipartimento dello sviluppo, dell&#8217;urbanistica, dell&#8217;ecologia e della gestione del territorio.<\/p>\n<p>In base alle risposte all\u2019Invito si acquisir\u00e0 una visione concreta delle intenzioni degli imprenditori di investire e operare nella Zona imprenditoriale Bodulovo.<\/p>\n<div id=\"attachment_14188\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" class=\"wp-image-14188 size-medium\" src=\"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/01\/aPredstavljanje-Poziv-poduzetnicima-na-iskazivanje-interesa-za-kupnju-lokacija-u-zoni-Bodulovo-1-600x400-600x400.jpg\" alt=\"\" \/><p class=\"wp-caption-text\">JANA SERTI\u0106, MARKO FILIPOVI\u0106 E DARIO DOBRILOVI\u0106<\/p><\/div>\n<p>In seguito all\u2019invito, ogni parte interessata ha l&#8217;opportunit\u00e0 di manifestare interesse per qualsiasi lotto, ovvero un terreno edificabile. Inoltre, manifestazioni di interesse da parte degli imprenditore non rappresentano l&#8217;assunzione di alcun obbligo, ma servono principalmente per l&#8217;analisi dell&#8217;interesse all&#8217;acquisto dei terreni, o l&#8217;intenzione di investire nella Zona.<\/p>\n<p>L&#8217;invito a manifestare interesse \u00e8 stato presentato dal sindaco di Fiume Marko Filipovi\u0107, dalla responsabile del Dipartimento dell&#8217;imprenditoria della Citt\u00e0 di Fiume Jana Serti\u0107 e dal consigliere superiore per lo sviluppo dell&#8217;imprenditoria Dario Dobrilovi\u0107.<\/p>\n<p>&#8220;La messa in funzione della Zona imprenditoriale Bodulovo consentir\u00e0 una maggiore competitivit\u00e0 delle piccole e medie imprese esistenti, aumenter\u00e0 il numero di nuovi posti di lavoro e incoragger\u00e0 nuovi investimenti. La nuova zona fornir\u00e0 anche una base di qualit\u00e0 per ulteriori affari delle aziende che acquistano un lotto, cio\u00e8 scelgono questo tipo di investimento&#8221;, ha affermato il sindaco di Fiume Marko Filipovi\u0107, aggiungendo che i lavori alle infrastrutture comunali dovrebbero essere ultimati a met\u00e0 di quest&#8217;anno quando un bando di gara per la vendita delle parcelle in questione dovrebbe essere pubblicato. &#8220;Il nostro ruolo come Citt\u00e0 di Fiume \u00e8 quello di creare le condizioni per lo sviluppo dell&#8217;imprenditoria e credo che con l\u2019assestamento di questa zona lo stiamo facendo con successo. Inoltre, vorrei sottolineare che questa \u00e8 solo la continuazione degli investimenti nello sviluppo delle piccole e medie imprese, dato che dalla fine del 2020 in via Milutin Bara\u010d opera l&#8217;incubatore imprenditoriale tecno-educativo Parco produttivo Torpedo, e quest&#8217;anno saranno avviati i lavori legati all&#8217;Incubatore di Startup per le tecnologie creative e l&#8217;industria IT Energana (Centrale energetica), che avr\u00e0 sede in via Ru\u017ei\u0107&#8221;, ha affermato Filipovi\u0107 e ha invitato tutti gli imprenditori interessati a manifestare il proprio interesse partecipando a questo invito pubblico.<\/p>\n<p>La Zona imprenditoriale Bodulovo si trova a 1,2 km dalla Tangenziale di Fiume, a 4 km dal porto di Fiume e dalla ferrovia e a 29 km dall&#8217;aeroporto di Fiume.<\/p>\n<div id=\"attachment_14189\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14189 size-medium\" src=\"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/01\/aPoduzetni\u010dka-zona-Bodulovo-izvod-iz-karte-\u0161ireg-podru\u010dja-450x600-450x600.png\" alt=\"\" width=\"450\" height=\"600\" srcset=\"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/01\/aPoduzetni\u010dka-zona-Bodulovo-izvod-iz-karte-\u0161ireg-podru\u010dja-450x600.png 450w, https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/01\/aPoduzetni\u010dka-zona-Bodulovo-izvod-iz-karte-\u0161ireg-podru\u010dja-450x600-300x400.png 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><p class=\"wp-caption-text\">zona imprenditoriale bodulovo<\/p><\/div>\n<p>Nella Zona imprenditoriale Bodulovo sono attualmente in corso i lavori per la realizzazione di infrastrutture comunali. L&#8217;appaltatore \u00e8 la GP Krk e la data prevista per il completamento dei lavori \u00e8 la fine di maggio di quest&#8217;anno.<\/p>\n<p>Simultaneamente con i lavori all&#8217;interno della Zona, l\u2019azienda municipalizzata \u201cViK\u201d sta costruendo l&#8217;infrastruttura di allacciamento idrico e fognario. L&#8217;ottenimento della documentazione per la messa in funzione dell&#8217;infrastruttura e la predisposizione della documentazione di gara per la vendita dei terreni si prevede secondo la dinamica dei lavori, ossia entro la fine del primo semestre di quest&#8217;anno.<\/p>\n<p>&#8220;Portando a termine il progetto, la Zona sar\u00e0 dotata di un&#8217;infrastruttura comunale completa, che sottintende la strada e il marciapiede nella Zona e il collegamento alle strade esistenti, l\u2019approvvigionamento idrico, la canalizzazione, il drenaggio delle acque piovane, l\u2019infrastruttura elettrica, l\u2019illuminazione pubblica, l\u2019infrastruttura di telecomunicazione, gasdotti e aree pubbliche verdi.<\/p>\n<p>Inoltre, al termine del progetto, gli imprenditori avranno a disposizione 9 terreni edificabili con una superficie totale di 19.694 mq, che variano in dimensioni da 1.029 mq a 8.558 mq. L&#8217;intera area della Zona si estende su 22.999 mq, e prevediamo di attivare la parte restante, che sar\u00e0 destinata anche ad attivit\u00e0 imprenditoriali, con finanziamenti da futuri bandi di gara per il cofinanziamento di progetti dai fondi dell\u2019UE, ha affermato Jana Serti\u0107, aggiungendo che vorrebbero vedere nella Zona imprenditoriale di Bodulovo lo sviluppo di una produzione specializzata, l\u2019attivit\u00e0 di servizio ad alto valore aggiunto, vale a dire l&#8217;industria informatica, l&#8217;industria blu con un&#8217;enfasi sul design e sulla costruzione navale e l&#8217;industria creativa.<\/p>\n<p>Il prezzo iniziale per metro quadrato nella Zona imprenditoriale di Bodulovo sar\u00e0 di 61 euro, con il prezzo finale da determinare in una procedura di gara che sar\u00e0 pubblicata attraverso il Bando di gara pubblico condotto dal Dipartimento dello sviluppo, dell&#8217;urbanistica, dell&#8217;ecologia e della gestione del territorio.<\/p>\n<p>Nell&#8217;ambito dell\u2019Invito a presentare manifestazioni di interesse rivolto agli imprenditori per l\u2019acquisto di terreni nella Zona imprenditoriale di Bodulovo, c&#8217;\u00e8 anche un modulo di registrazione che tutti gli imprenditori interessati devono presentare alla Citt\u00e0 di Fiume entro il 1 marzo di quest&#8217;anno via e-mail a <a href=\"http:\/\/da&#114;&#105;&#111;&#46;&#100;&#x6f;&#x62;&#x72;&#x69;&#x6c;&#x6f;&#x76;ic&#64;r&#105;&#106;&#101;&#107;&#97;&#x2e;&#x68;&#x72;.\">&#x64;&#x61;&#x72;&#105;&#111;&#46;do&#x62;&#x72;&#x69;&#x6c;&#111;&#118;ic&#x40;&#x72;&#x69;&#x6a;&#101;&#107;a&#46;&#x68;&#x72;. <\/a>o <a href=\"&#109;a&#x69;l&#x74;o&#x3a;p&#x6f;&#100;&#x75;&#122;&#x65;&#116;&#x6e;&#105;s&#116;v&#x6f;&#64;&#x72;i&#x6a;&#101;&#x6b;&#97;&#x2e;&#104;&#x72;\">poduzetnistv&#111;&#64;&#114;&#105;&#106;&#101;&#107;&#97;&#46;&#104;&#114;<\/a>.<\/p>\n<p>Finora per la Zona imprenditoriale Bodulovo sono stati assicurati 8 milioni di sovvenzioni a fondo perduto dell&#8217;UE.<\/p>\n<p>Le attivit\u00e0 per la realizzazione della Zona imprenditoriale Bodulovo sono iniziate nel 2003 con la redazione dello Studio programmatico per la Zona, che \u00e8 stato la base per la stesura della documentazione di pianificazione territoriale, ovvero il concetto di assetto della zona. La Citt\u00e0 di Fiume ha investito circa 8 milioni di kune nell&#8217;acquisto dei terreni, nella preparazione della documentazione progettuale e nei lavori di riempimento del terreno.<\/p>\n<p>Dopo aver completato la preparazione del terreno, nel 2017, la Citt\u00e0 di Fiume ha candidato il suo progetto \u201cCostruzione delle infrastrutture comunali nella zona imprenditoriale Bodulovo\u201d in risposta al bando pubblicato dal Ministero dell\u2019economia, dell\u2019imprenditoria e dell\u2019artigianato. Il valore complessivo di questo progetto ammonta a 11.258.233,00 kune, di cui 5.710.343,18 kune sono sovvenzioni a fondo perduto dell&#8217;UE assicurate con Fondi strutturali, il Fondo europeo di sviluppo regionale attraverso il programma operativo &#8220;Competitivit\u00e0 e coesione&#8221;. I fondi rimanenti sono stati assicurati dalla Citt\u00e0 di Fiume.<\/p>\n<p>Nel mese di dicembre 2020 con questo progetto abbiamo partecipato all\u2019Invito pubblico per il cofinanziamento dell\u2019implementazione di progetti dell&#8217;UE a livello regionale e locale per il 2020, e nel mese di novembre 2021 \u00e8 stato firmato l\u2019Accordo di cofinanziamento per l\u2019implementazione di progetti europei con il Ministero dello sviluppo regionale e dei fondi dell&#8217;UE per l\u2019approvata sovvenzione a fondo perduto nell\u2019importo di 2.336.049,49 kune.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-13024 size-full\" src=\"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2021\/05\/Kohezijski-fond-1000x377.jpg\" alt=\"\" width=\"1000\" height=\"377\" srcset=\"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2021\/05\/Kohezijski-fond-1000x377.jpg 1000w, https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2021\/05\/Kohezijski-fond-1000x377-600x226.jpg 600w, https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2021\/05\/Kohezijski-fond-1000x377-768x290.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si tratta dell\u2019invito attraverso il quale gli imprenditori presentano manifestazioni di interesse all\u2019acquisto di terreni edificabili, ovvero la propria intenzione di investire e operare nella Zona imprenditoriale di Bodulovo. L\u2019Invito rimane aperto fino al 1 marzo 2022.<\/p>\n","protected":false},"author":89,"featured_media":14187,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[976],"tags":[1040,132,1309,1310,1308],"class_list":["post-14183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articoli","tag-fondi-strutturali-e-di-investimento-europei","tag-invito-pubblico","tag-lotti","tag-progetto-ue","tag-zona-imprenditoriale-bodulovo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pubblicato l\u2019Invito a presentare manifestazioni di interesse rivolto agli imprenditori per l\u2019acquisto di lotti nella Zona imprenditoriale Bodulovo - Citt\u00e0 di Fiume<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pubblicato l\u2019Invito a presentare manifestazioni di interesse rivolto agli imprenditori per l\u2019acquisto di lotti nella Zona imprenditoriale Bodulovo - Citt\u00e0 di Fiume\" \/>\n<meta property=\"og:description\" content=\"Si tratta dell\u2019invito attraverso il quale gli imprenditori presentano manifestazioni di interesse all\u2019acquisto di terreni edificabili, ovvero la propria intenzione di investire e operare nella Zona imprenditoriale di Bodulovo. L\u2019Invito rimane aperto fino al 1 marzo 2022.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/\" \/>\n<meta property=\"og:site_name\" content=\"Citt\u00e0 di Fiume\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-31T11:03:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-19T09:40:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/01\/aPredstavljanje-Poziv-poduzetnicima-na-iskazivanje-interesa-za-kupnju-lokacija-u-zoni-Bodulovo-2-901x600.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"901\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mbembic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"mbembic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/\",\"url\":\"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/\",\"name\":\"Pubblicato l\u2019Invito a presentare manifestazioni di interesse rivolto agli imprenditori per l\u2019acquisto di lotti nella Zona imprenditoriale Bodulovo - Citt\u00e0 di Fiume\",\"isPartOf\":{\"@id\":\"https:\/\/www.rijeka.hr\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/01\/aPredstavljanje-Poziv-poduzetnicima-na-iskazivanje-interesa-za-kupnju-lokacija-u-zoni-Bodulovo-2-901x600.jpg\",\"datePublished\":\"2022-01-31T11:03:38+00:00\",\"dateModified\":\"2022-05-19T09:40:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.rijeka.hr\/it\/#\/schema\/person\/c6f2fe4ba52af1df0e9a2b0a22d63cc0\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/#primaryimage\",\"url\":\"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/01\/aPredstavljanje-Poziv-poduzetnicima-na-iskazivanje-interesa-za-kupnju-lokacija-u-zoni-Bodulovo-2-901x600.jpg\",\"contentUrl\":\"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/01\/aPredstavljanje-Poziv-poduzetnicima-na-iskazivanje-interesa-za-kupnju-lokacija-u-zoni-Bodulovo-2-901x600.jpg\",\"width\":901,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna stranica\",\"item\":\"https:\/\/www.rijeka.hr\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pubblicato l\u2019Invito a presentare manifestazioni di interesse rivolto agli imprenditori per l\u2019acquisto di lotti nella Zona imprenditoriale Bodulovo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.rijeka.hr\/it\/#website\",\"url\":\"https:\/\/www.rijeka.hr\/it\/\",\"name\":\"Citt\u00e0 di Fiume\",\"description\":\"Portale web della Citta&#039; di Fiume\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.rijeka.hr\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.rijeka.hr\/it\/#\/schema\/person\/c6f2fe4ba52af1df0e9a2b0a22d63cc0\",\"name\":\"mbembic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.rijeka.hr\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3ce3ce6ed89053defb3e592d3a5f1f9f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3ce3ce6ed89053defb3e592d3a5f1f9f?s=96&d=mm&r=g\",\"caption\":\"mbembic\"},\"sameAs\":[\"https:\/\/www.rijeka.hr\/\"],\"url\":\"https:\/\/www.rijeka.hr\/it\/author\/mbembic\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pubblicato l\u2019Invito a presentare manifestazioni di interesse rivolto agli imprenditori per l\u2019acquisto di lotti nella Zona imprenditoriale Bodulovo - Citt\u00e0 di Fiume","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/","og_locale":"it_IT","og_type":"article","og_title":"Pubblicato l\u2019Invito a presentare manifestazioni di interesse rivolto agli imprenditori per l\u2019acquisto di lotti nella Zona imprenditoriale Bodulovo - Citt\u00e0 di Fiume","og_description":"Si tratta dell\u2019invito attraverso il quale gli imprenditori presentano manifestazioni di interesse all\u2019acquisto di terreni edificabili, ovvero la propria intenzione di investire e operare nella Zona imprenditoriale di Bodulovo. L\u2019Invito rimane aperto fino al 1 marzo 2022.","og_url":"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/","og_site_name":"Citt\u00e0 di Fiume","article_published_time":"2022-01-31T11:03:38+00:00","article_modified_time":"2022-05-19T09:40:16+00:00","og_image":[{"width":901,"height":600,"url":"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/01\/aPredstavljanje-Poziv-poduzetnicima-na-iskazivanje-interesa-za-kupnju-lokacija-u-zoni-Bodulovo-2-901x600.jpg","type":"image\/jpeg"}],"author":"mbembic","twitter_card":"summary_large_image","twitter_misc":{"Written by":"mbembic","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/","url":"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/","name":"Pubblicato l\u2019Invito a presentare manifestazioni di interesse rivolto agli imprenditori per l\u2019acquisto di lotti nella Zona imprenditoriale Bodulovo - Citt\u00e0 di Fiume","isPartOf":{"@id":"https:\/\/www.rijeka.hr\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/#primaryimage"},"image":{"@id":"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/01\/aPredstavljanje-Poziv-poduzetnicima-na-iskazivanje-interesa-za-kupnju-lokacija-u-zoni-Bodulovo-2-901x600.jpg","datePublished":"2022-01-31T11:03:38+00:00","dateModified":"2022-05-19T09:40:16+00:00","author":{"@id":"https:\/\/www.rijeka.hr\/it\/#\/schema\/person\/c6f2fe4ba52af1df0e9a2b0a22d63cc0"},"breadcrumb":{"@id":"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/#primaryimage","url":"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/01\/aPredstavljanje-Poziv-poduzetnicima-na-iskazivanje-interesa-za-kupnju-lokacija-u-zoni-Bodulovo-2-901x600.jpg","contentUrl":"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/01\/aPredstavljanje-Poziv-poduzetnicima-na-iskazivanje-interesa-za-kupnju-lokacija-u-zoni-Bodulovo-2-901x600.jpg","width":901,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.rijeka.hr\/it\/pubblicato-linvito-presentare-manifestazioni-di-interesse-rivolto-agli-imprenditori-per-lacquisto-di-lotti-nella-zona-imprenditoriale-di-bodulovo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna stranica","item":"https:\/\/www.rijeka.hr\/it\/"},{"@type":"ListItem","position":2,"name":"Pubblicato l\u2019Invito a presentare manifestazioni di interesse rivolto agli imprenditori per l\u2019acquisto di lotti nella Zona imprenditoriale Bodulovo"}]},{"@type":"WebSite","@id":"https:\/\/www.rijeka.hr\/it\/#website","url":"https:\/\/www.rijeka.hr\/it\/","name":"Citt\u00e0 di Fiume","description":"Portale web della Citta&#039; di Fiume","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rijeka.hr\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.rijeka.hr\/it\/#\/schema\/person\/c6f2fe4ba52af1df0e9a2b0a22d63cc0","name":"mbembic","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rijeka.hr\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3ce3ce6ed89053defb3e592d3a5f1f9f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ce3ce6ed89053defb3e592d3a5f1f9f?s=96&d=mm&r=g","caption":"mbembic"},"sameAs":["https:\/\/www.rijeka.hr\/"],"url":"https:\/\/www.rijeka.hr\/it\/author\/mbembic\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/posts\/14183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/comments?post=14183"}],"version-history":[{"count":3,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/posts\/14183\/revisions"}],"predecessor-version":[{"id":15040,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/posts\/14183\/revisions\/15040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/media\/14187"}],"wp:attachment":[{"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/media?parent=14183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/categories?post=14183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/tags?post=14183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}