{"id":15155,"date":"2022-06-10T13:00:59","date_gmt":"2022-06-10T11:00:59","guid":{"rendered":"https:\/\/www.rijeka.hr\/it\/?p=15155"},"modified":"2022-06-20T13:06:01","modified_gmt":"2022-06-20T11:06:01","slug":"la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume","status":"publish","type":"post","link":"https:\/\/www.rijeka.hr\/it\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\/","title":{"rendered":"La conferenza Blue Growth (Crescita blu) dedicata al futuro ACI Marina a Fiume"},"content":{"rendered":"<p>La conferenza, organizzata dal Gruppo L\u00fcrssen e dall\u2019ACI, dalla Gitone Kvarner, dall\u2019ACI-GITONE e dal quotidiano fiumano Novi list, tenutasi nel terminal in Molo longo, ha riunito esperti dell&#8217;industria marittima, della cantieristica navale, della digitalizzazione e altre figure chiave del turismo e degli affari marittimi croati, era guidata dai rappresentanti del Gruppo Lurssen e dell&#8217;ACI, che hanno presentato i progetti la cui attuazione cambier\u00e0 l\u2019immagine del Quarnero nei prossimi anni.<\/p>\n<p>La conferenza \u00e8 stata aperta dai discorsi di benvenuto tenuti da Teuta Duleti\u0107, direttore esecutivo del Lurssen Design Center Kvarner, Ivan Herak, membro del consiglio di amministrazione responsabile per le finanze, il diritto societario e le risorse umane, dell\u2019ACI, Zlatko Komadina, presidente della Regione litoraneo montana e Vladimir Savi\u0107, consigliere per l&#8217;economia del Primo Ministro della Repubblica di Croazia, che hanno accolto con favore i prossimi progetti e investimenti del Gruppo Lurssen nel Quarnero. Uno dei temi pi\u00f9 importanti \u00e8 stato il futuro ACI Marina a Fiume, che sar\u00e0 il pi\u00f9 grande investimento finora nel turismo nautico in Croazia e che creer\u00e0 oltre 130 nuovi posti di lavoro nel marina.<\/p>\n<div id=\"attachment_15160\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" class=\"wp-image-15160 size-medium\" src=\"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Konferencija-Blue-growth-o-budu\u0107oj-ACI-marini-Rijeka-2-600x400-600x400.jpg\" alt=\"\" \/><p class=\"wp-caption-text\">ALLA CONFERENZA HANNO PARTECIPATO IL SINDACO DI FIUME MARKO FILIPOVI\u0106 E L&#8217;EX SINDACO VOJKO OBERSNEL<\/p><\/div>\n<p>Nel coso della prima discussione panel particolare attenzione \u00e8 stata rivolta all&#8217;era digitale e all&#8217;impatto dell&#8217;introduzione delle tecnologie digitali nell&#8217;industria marittima, mentre la seconda discussione panel ha aperto alcune altre importanti questioni relative all&#8217;uso dell&#8217;idrogeno e ai vantaggi dello sviluppo del potenziale di un&#8217;economia dell\u2019idrogeno che \u00e8 armonizzata con gli obiettivi della Strategia Europea per l&#8217;Idrogeno.<\/p>\n<p>La conferenza si \u00e8 conclusa con la terza discussione panel, incentrata sul futuro ACI Marina a Fiume. Kristijan Pavi\u0107, presidente del consiglio di amministrazione dell\u2019ACI e Josip Ostrogovi\u0107, membro del consiglio di amministrazione responsabile per gli investimenti, il marketing e la vendita al dettaglio dell\u2019ACI, hanno sottolineato che l&#8217;ACI Marina stabilir\u00e0 nuovi standard nella regione quando si parla di costruzione di porti per il turismo nautico. Uno dei principali potenziali di sviluppo in questo senso \u00e8 sicuramente lo sviluppo di nuove tecnologie. L&#8217;ACI Marina sar\u00e0 un porto verde e completamente digitalizzato e un centro per lo sviluppo di nuove tecnologie che saranno applicate in futuro nel turismo nautico, sia a bordo delle navi che nei porti turistici.<\/p>\n<p>Il sindaco di Fiume, Marko Filipovi\u0107, ha sottolineato che la costruzione dell&#8217;ACI Marina a Fiume, cos\u00ec come numerosi progetti privati cittadini e statali che si svolgono sulla costa, porteranno cambiamenti nella vita cittadina.<\/p>\n<p>&#8220;Sono i progetti che cambiano l\u2019immagine della citt\u00e0, soprattutto se la guardiamo dal mare. Con la loro realizzazione riportiamo Fiume al mare, a cui appartiene, perch\u00e9 il mare \u00e8 nel nostro DNA: la citt\u00e0 si sviluppava per lo pi\u00f9 nei periodi in cui era orientata verso il mare&#8221;, ha affermato il sindaco Filipovi\u0107, esprimendo la sua soddisfazione per il significativo investimento nell&#8217;ACI Marina. Tutti i progetti attualmente in corso o che inizieranno presto sul territorio cittadino in collaborazione con tutti i partner coinvolti, sono stati preparati da molto tempo, quindi l&#8217;ACI Marina \u00e8 da tempo iscritto nella documentazione di pianificazione territoriale della citt\u00e0.<\/p>\n<div id=\"attachment_15161\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15161 size-medium\" src=\"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Konferencija-Blue-growth-o-budu\u0107oj-ACI-marini-Rijeka-4-600x400-600x400.jpg\" alt=\"\" width=\"600\" height=\"400\" \/><p class=\"wp-caption-text\">La conferenza si \u00e8 conclusa con la terza discussione panel, incentrata sul futuro ACI Marina a Fiume.<\/p><\/div>\n<p>Il sindaco ha detto che la nave ristrutturata Galeb sar\u00e0 presto ormeggiata al Molo Long ed ha espresso la convinzione che diventer\u00e0 una vera attrazione turistica e la realizzazione del progetto \u017dabica occidentale cambier\u00e0 il volto della citt\u00e0. In risposta al bando di gara pubblicato dalla Citt\u00e0 di Fiume, \u00e8 pervenuta un&#8217;offerta per la realizzazione del progetto da parte di un partner privato.<\/p>\n<p>Johannes B\u00f6ck, presidente del consiglio di amministrazione della GITONE Kvarner, ha sottolineato di voler trasformare Porto Baross in un porto verde e digitale.<\/p>\n<p>&#8220;In parallelo con i nostri sforzi di costruzione navale e ingegneria, inizieremo a plasmare il futuro della zona costiera di Fiume investendo nel nuovo marina nel porto. Ci\u00f2 contribuir\u00e0 ai nostri obiettivi di un futuro verde e digitale e svolger\u00e0 un ruolo chiave nello sviluppo della citt\u00e0, soprattutto in termini di competitivit\u00e0 nautica e turistica\u201d, ha affermato.<\/p>\n<p>A condizione che tutto vada secondo i piani e senza imprevisti, l&#8217;inizio dei lavori di costruzione potrebbe essere intorno alla met\u00e0 del prossimo anno. La parte marittima del porto turistico potrebbe essere aperta nel 2024 e l&#8217;intero porto turistico nel 2026. La parte marittima del marina inizier\u00e0 a funzionare indipendentemente dal contenuto a terra\u201d, ha annunciato An\u0111elko Petrini\u0107, direttore dell\u2019ACI-GITONE.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sindaco di Fiume, Marko Filipovi\u0107, ha partecipato alla conferenza &#8220;Blue Growth &#8211; Kvarner 2030&#8221;, nel corso della quale uno dei temi pi\u00f9 importanti \u00e8 stata la costruzione dell&#8217;ACI Marina a Fiume.<\/p>\n","protected":false},"author":8,"featured_media":15158,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[976],"tags":[1569,1568,1571,1547,1570],"class_list":["post-15155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articoli","tag-aci-marina-a-fiume","tag-conferenza-blue-growth-crescita-blu","tag-economia-dellidrogeno","tag-gruppo-lurssen","tag-strategia-europea-per-lidrogeno"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La conferenza Blue Growth (Crescita blu) dedicata al futuro ACI Marina a Fiume - Citt\u00e0 di Fiume<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rijeka.hr\/it\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La conferenza Blue Growth (Crescita blu) dedicata al futuro ACI Marina a Fiume - Citt\u00e0 di Fiume\" \/>\n<meta property=\"og:description\" content=\"Il sindaco di Fiume, Marko Filipovi\u0107, ha partecipato alla conferenza &quot;Blue Growth - Kvarner 2030&quot;, nel corso della quale uno dei temi pi\u00f9 importanti \u00e8 stata la costruzione dell&#039;ACI Marina a Fiume.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rijeka.hr\/it\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\/\" \/>\n<meta property=\"og:site_name\" content=\"Citt\u00e0 di Fiume\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-10T11:00:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-20T11:06:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Konferencija-Blue-growth-o-budu\u0107oj-ACI-marini-Rijeka-1-900x600.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sradovic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"sradovic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\\\/\"},\"author\":{\"name\":\"sradovic\",\"@id\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/#\\\/schema\\\/person\\\/f944eacc70b6a69bc142d9389862b37b\"},\"headline\":\"La conferenza Blue Growth (Crescita blu) dedicata al futuro ACI Marina a Fiume\",\"datePublished\":\"2022-06-10T11:00:59+00:00\",\"dateModified\":\"2022-06-20T11:06:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\\\/\"},\"wordCount\":769,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/Konferencija-Blue-growth-o-budu\u0107oj-ACI-marini-Rijeka-1-900x600.jpg\",\"keywords\":[\"ACI Marina a Fiume\",\"conferenza Blue Growth (Crescita blu)\",\"economia dell\u2019idrogeno\",\"gruppo L\u00fcrssen\",\"Strategia Europea per l'Idrogeno\"],\"articleSection\":[\"Articoli\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\\\/\",\"url\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\\\/\",\"name\":\"La conferenza Blue Growth (Crescita blu) dedicata al futuro ACI Marina a Fiume - Citt\u00e0 di Fiume\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/Konferencija-Blue-growth-o-budu\u0107oj-ACI-marini-Rijeka-1-900x600.jpg\",\"datePublished\":\"2022-06-10T11:00:59+00:00\",\"dateModified\":\"2022-06-20T11:06:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/#\\\/schema\\\/person\\\/f944eacc70b6a69bc142d9389862b37b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/Konferencija-Blue-growth-o-budu\u0107oj-ACI-marini-Rijeka-1-900x600.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/Konferencija-Blue-growth-o-budu\u0107oj-ACI-marini-Rijeka-1-900x600.jpg\",\"width\":900,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna stranica\",\"item\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La conferenza Blue Growth (Crescita blu) dedicata al futuro ACI Marina a Fiume\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/\",\"name\":\"Citt\u00e0 di Fiume\",\"description\":\"Portale web della Citta&#039; di Fiume\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/#\\\/schema\\\/person\\\/f944eacc70b6a69bc142d9389862b37b\",\"name\":\"sradovic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4e39f668c95fc7f4d6c0101e9e24ae2122b243f3165c99346d6c56c7c5a675a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4e39f668c95fc7f4d6c0101e9e24ae2122b243f3165c99346d6c56c7c5a675a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4e39f668c95fc7f4d6c0101e9e24ae2122b243f3165c99346d6c56c7c5a675a?s=96&d=mm&r=g\",\"caption\":\"sradovic\"},\"url\":\"https:\\\/\\\/www.rijeka.hr\\\/it\\\/author\\\/sradovic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La conferenza Blue Growth (Crescita blu) dedicata al futuro ACI Marina a Fiume - Citt\u00e0 di Fiume","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rijeka.hr\/it\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\/","og_locale":"it_IT","og_type":"article","og_title":"La conferenza Blue Growth (Crescita blu) dedicata al futuro ACI Marina a Fiume - Citt\u00e0 di Fiume","og_description":"Il sindaco di Fiume, Marko Filipovi\u0107, ha partecipato alla conferenza \"Blue Growth - Kvarner 2030\", nel corso della quale uno dei temi pi\u00f9 importanti \u00e8 stata la costruzione dell'ACI Marina a Fiume.","og_url":"https:\/\/www.rijeka.hr\/it\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\/","og_site_name":"Citt\u00e0 di Fiume","article_published_time":"2022-06-10T11:00:59+00:00","article_modified_time":"2022-06-20T11:06:01+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Konferencija-Blue-growth-o-budu\u0107oj-ACI-marini-Rijeka-1-900x600.jpg","type":"image\/jpeg"}],"author":"sradovic","twitter_card":"summary_large_image","twitter_misc":{"Written by":"sradovic","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rijeka.hr\/it\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\/#article","isPartOf":{"@id":"https:\/\/www.rijeka.hr\/it\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\/"},"author":{"name":"sradovic","@id":"https:\/\/www.rijeka.hr\/it\/#\/schema\/person\/f944eacc70b6a69bc142d9389862b37b"},"headline":"La conferenza Blue Growth (Crescita blu) dedicata al futuro ACI Marina a Fiume","datePublished":"2022-06-10T11:00:59+00:00","dateModified":"2022-06-20T11:06:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rijeka.hr\/it\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\/"},"wordCount":769,"commentCount":0,"image":{"@id":"https:\/\/www.rijeka.hr\/it\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Konferencija-Blue-growth-o-budu\u0107oj-ACI-marini-Rijeka-1-900x600.jpg","keywords":["ACI Marina a Fiume","conferenza Blue Growth (Crescita blu)","economia dell\u2019idrogeno","gruppo L\u00fcrssen","Strategia Europea per l'Idrogeno"],"articleSection":["Articoli"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rijeka.hr\/it\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rijeka.hr\/it\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\/","url":"https:\/\/www.rijeka.hr\/it\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\/","name":"La conferenza Blue Growth (Crescita blu) dedicata al futuro ACI Marina a Fiume - Citt\u00e0 di Fiume","isPartOf":{"@id":"https:\/\/www.rijeka.hr\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rijeka.hr\/it\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\/#primaryimage"},"image":{"@id":"https:\/\/www.rijeka.hr\/it\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Konferencija-Blue-growth-o-budu\u0107oj-ACI-marini-Rijeka-1-900x600.jpg","datePublished":"2022-06-10T11:00:59+00:00","dateModified":"2022-06-20T11:06:01+00:00","author":{"@id":"https:\/\/www.rijeka.hr\/it\/#\/schema\/person\/f944eacc70b6a69bc142d9389862b37b"},"breadcrumb":{"@id":"https:\/\/www.rijeka.hr\/it\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rijeka.hr\/it\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rijeka.hr\/it\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\/#primaryimage","url":"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Konferencija-Blue-growth-o-budu\u0107oj-ACI-marini-Rijeka-1-900x600.jpg","contentUrl":"https:\/\/www.rijeka.hr\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Konferencija-Blue-growth-o-budu\u0107oj-ACI-marini-Rijeka-1-900x600.jpg","width":900,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.rijeka.hr\/it\/la-conferenza-blue-growth-crescita-blu-dedicata-al-futuro-aci-marina-fiume\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna stranica","item":"https:\/\/www.rijeka.hr\/it\/"},{"@type":"ListItem","position":2,"name":"La conferenza Blue Growth (Crescita blu) dedicata al futuro ACI Marina a Fiume"}]},{"@type":"WebSite","@id":"https:\/\/www.rijeka.hr\/it\/#website","url":"https:\/\/www.rijeka.hr\/it\/","name":"Citt\u00e0 di Fiume","description":"Portale web della Citta&#039; di Fiume","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rijeka.hr\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.rijeka.hr\/it\/#\/schema\/person\/f944eacc70b6a69bc142d9389862b37b","name":"sradovic","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f4e39f668c95fc7f4d6c0101e9e24ae2122b243f3165c99346d6c56c7c5a675a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4e39f668c95fc7f4d6c0101e9e24ae2122b243f3165c99346d6c56c7c5a675a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4e39f668c95fc7f4d6c0101e9e24ae2122b243f3165c99346d6c56c7c5a675a?s=96&d=mm&r=g","caption":"sradovic"},"url":"https:\/\/www.rijeka.hr\/it\/author\/sradovic\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/posts\/15155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/comments?post=15155"}],"version-history":[{"count":3,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/posts\/15155\/revisions"}],"predecessor-version":[{"id":15163,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/posts\/15155\/revisions\/15163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/media\/15158"}],"wp:attachment":[{"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/media?parent=15155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/categories?post=15155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rijeka.hr\/it\/wp-json\/wp\/v2\/tags?post=15155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}